{"id":10219,"date":"2024-06-05T09:01:01","date_gmt":"2024-06-05T12:01:01","guid":{"rendered":"http:\/\/www.searadecristo.com.br\/portal\/?p=10219"},"modified":"2024-06-05T09:01:01","modified_gmt":"2024-06-05T12:01:01","slug":"uma-parabola-sobre-israel-2","status":"publish","type":"post","link":"http:\/\/www.searadecristo.com.br\/portal\/uma-parabola-sobre-israel-2\/","title":{"rendered":"Uma par\u00e1bola sobre Israel"},"content":{"rendered":"<p><strong>EBD \u2013 <\/strong>Adolescentes<strong> &#8211; EDI\u00c7\u00c3O: 1<\/strong><strong>78<\/strong>\u00a0&#8211; 2\u00ba Trimestre &#8211; Ano: 2022 &#8211; Editora: CPAD<\/p>\n<p><strong>LI\u00c7\u00c3O &#8211; 09<\/strong> \u2013 02 de junho de 2024<\/p>\n<p><strong>TEXTO B\u00cdBLICO<\/strong><\/p>\n<p>Lucas 13.6-9<\/p>\n<p><strong>DESTAQUE<\/strong><\/p>\n<p>\u201cE a natureza gloriosa do meu Pai se revela quando voc\u00eas produzem muitos frutos e assim mostram que s\u00e3o meus disc\u00edpulos.\u201d <strong>Jo\u00e3o 15.8<\/strong><\/p>\n<p><strong>LEITURA DEVOCIONAL<\/strong><\/p>\n<p><strong>Segunda-feira<\/strong> &#8211; Sl 1.1-3<br \/>\n<strong>Ter\u00e7a-feira &#8211;<\/strong>\u00a0Jo 15.1-5<br \/>\n<strong>Quarta-feira &#8211; <\/strong>Lc 9.23,24<br \/>\n<strong>Quinta-feira &#8211;<\/strong> II Pe 3.9<br \/>\n<strong>Sexta-feira &#8211; <\/strong>At 3.19<br \/>\n<strong>S\u00e1bado <\/strong>&#8211; Mc 11.20-22<\/p>\n<p><strong>I. UMA ADVERT\u00caNCIA SOBRE O ARREPENDIMENTO<\/strong><\/p>\n<p>O cap\u00edtulo 13 do Evangelho de Lucas come\u00e7a com algumas pessoas abordando Jesus para falar sobre o massacre promovido por Pilatos (o governador romano da Jud\u00e9ia) contra algumas pessoas da Galileia, no momento em que sacrificavam no tempo de Jerusal\u00e9m (v.1). Logo em seguida, Jesus lhes relembra o tr\u00e1gico epis\u00f3dio acontecido no bairro de Silo\u00e9, onde uma torre caiu e dezoito pessoas foram a \u00f3bito (v.4). Jesus, ent\u00e3o, aproveita essas duas trag\u00e9dias para advertir seus ouvintes sobre a necessidade de olharem para suas pr\u00f3prias vidas e se arrependerem dos seus pecados enquanto h\u00e1 tempo (vv.3,5).<br \/>\nA grande quest\u00e3o levantada por Jesus \u00e9 que precisamos fazer uma autoan\u00e1lise da vida que estamos vivendo e sermos sinceros diante de Deus. O pecado, por menor que seja ou inofensivo que pare\u00e7a aos nossos olhos, \u00e9 sempre uma afronta \u00e0 santidade de Deus e, por isso, \u00e9 grave e requer imediato arrependimento,\u00a0caso contr\u00e1rio, no tempo oportuno, o ju\u00edzo do Deus santo vir\u00e1 sobre n\u00f3s. Aceitemos, diariamente, o convite ao arrependimento do Evangelho do Senhor Jesus Cristo (Mt 3.2,8; Mc 6.12).<\/p>\n<p><strong>II. <\/strong><strong>UMA DEMONSTRA\u00c7\u00c3O DE PACI\u00caNCIA<\/strong><\/p>\n<p>De acordo com a par\u00e1bola, o dono de uma terra tinha uma expectativa para a figueira cultivada no meio de sua planta\u00e7\u00e3o de uvas (Lc 13.6). Ela tinha tudo que precisava para dar frutos no tempo determinado. Entretanto, para a tristeza do dono da terra, aquela que deveria produzir em abund\u00e2ncia n\u00e3o dava nenhum sinal de frutos. Muito paciente, o dono, com suas expectativas frustradas, declara seu descontentamento: \u201c[\u2026] J\u00e1 faz tr\u00eas anos seguidos que venho buscar figos nesta figueira e n\u00e3o encontro nenhum [\u2026]\u201d (v.7). Decidido a cort\u00e1-la, o dono aceita a interven\u00e7\u00e3o do trabalhador da vinha que pede por mais um tempo de toler\u00e2ncia, ou seja, uma segunda chance para a \u00e1rvore infrut\u00edfera (v.8).<br \/>\nEssa par\u00e1bola faz refer\u00eancia ao povo de Israel, que obstinadamente escolheu rejeitar o Messias enviado por Deus. Durante sua primeira vinda \u00e0 Terra, Jesus foi ignorado, perseguido e morto. Ele convocou seus compatriotas ao arrependimento e demonstrou com atitudes concretas o amor e a miseric\u00f3rdia do Pai, mas eles se recusavam a dar frutos para Deus. Mas, segundo o texto b\u00edblico, o nosso Deus tem demonstrado paci\u00eancia: \u201c[\u2026] porque n\u00e3o quer que ningu\u00e9m seja destru\u00eddo, mas deseja que todos se arrependam dos seus pecados\u201d (2 Pe 3.9). Se n\u00e3o fosse a miseric\u00f3rdia paciente de Deus e a intercess\u00e3o de Cristo tanto por Israel, quanto pela Igreja e pela humanidade, j\u00e1 ter\u00edamos perecido. Todos n\u00f3s recebemos uma segunda oportunidade de Deus e n\u00e3o devemos desprez\u00e1-la. N\u00e3o podemos abusar de sua santa paci\u00eancia, pois como est\u00e1 expl\u00edcito na par\u00e1bola, onde falta arrependimento, o ju\u00edzo \u00e9 inevit\u00e1vel.<br \/>\nO dono da figueira atende ao pedido do trabalhador e estende o tempo da paci\u00eancia. Entretanto, ele \u00e9 claro, diante da oportunidade concedida: \u201cSe no ano que vem ela der figos, muito bem. Se n\u00e3o der, ent\u00e3o mande cort\u00e1-la\u201d (Lc 13.9). Essa hist\u00f3ria ilustra que, embora Deus seja gracioso e misericordioso ao dar ao seu povo tempo poro se arrepender, vir at\u00e9 Ele e crescer nELe, a sua paci\u00eancia n\u00e3o durar\u00e1 para sempre.<\/p>\n<p><strong>III. <\/strong><strong>UM CONVITE \u00c0 FRUTIFICA\u00c7\u00c3O<\/strong><\/p>\n<p>Como vimos, Deus procura frutos entre seus filhos. Toda tentativa permanente de desculpas para uma vida infrut\u00edfera ser\u00e1 ineficaz, pois Ele nos conhece e tem nos dado todas as condi\u00e7\u00f5es necess\u00e1rias para frutificar no seu Reino. Ele nos deu sua Palavra, seu Esp\u00edrito, sua presen\u00e7a, seu poder, por isso espera de n\u00f3s muitos frutos (Jo 15.5-8), e jamais se contentar\u00e1 apenas com folhas e galhos, ou seja, com uma vida espiritual de apar\u00eancia. Jesus disse: \u201cN\u00e3o foram voc\u00eas que me escolheram; pelo contr\u00e1rio, fui eu que os escolhi para que v\u00e3o e deem fruto e que esse fruto n\u00e3o se perca\u201d (Jo 15.16). \u00c9 importante que entendamos que a frutifica\u00e7\u00e3o espiritual depende fundamentalmente da nossa comunh\u00e3o com Jesus Cristo (Jo 15.5). \u00c9 preciso viver para gl\u00f3ria de Deus, pois \u201cquem p\u00f5e os seus pr\u00f3prios interesses em primeiro lugar nunca ter\u00e1 a vida verdadeira; mas quem esquece a si mesmo por minha causa ter\u00e1 a vida verdadeira\u201d (Lc 9.24).<\/p>\n<p><strong>CONCLUS\u00c3O<\/strong><\/p>\n<p>O nosso Deus \u00e9 misericordioso com os pecadores. Mas para aqueles que o rejeitam, Ele n\u00e3o ser\u00e1 misericordioso para sempre. Haver\u00e1 um dia que ser\u00e3o punidos os que vivem como se Ele n\u00e3o existisse. Por essa raz\u00e3o, somos chamados ao arrependimento sincero e verdadeiro e \u00e0 uma vida marcada por frutos dignos da convers\u00e3o que experimentamos.<\/p>\n<h2><\/h2>\n<p>&nbsp;<\/p>\n<p><strong>Postado por: <\/strong>Pr. Ademilson Braga<\/p>\n<p style=\"text-align: right;\"><strong>Fonte: <\/strong>Editora CPAD<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EBD \u2013 Adolescentes &#8211; EDI\u00c7\u00c3O: 178\u00a0&#8211; 2\u00ba Trimestre &#8211; Ano: 2022 &#8211; Editora: CPAD LI\u00c7\u00c3O &#8211; 09 \u2013 02 de junho de 2024 TEXTO B\u00cdBLICO Lucas 13.6-9 DESTAQUE \u201cE a natureza gloriosa do meu Pai se revela quando voc\u00eas produzem muitos frutos e assim mostram que s\u00e3o meus disc\u00edpulos.\u201d Jo\u00e3o 15.8 LEITURA DEVOCIONAL Segunda-feira &#8211; [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10220,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[972,7],"tags":[],"class_list":["post-10219","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-adolescente","category-e-b-d"],"_links":{"self":[{"href":"http:\/\/www.searadecristo.com.br\/portal\/wp-json\/wp\/v2\/posts\/10219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.searadecristo.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.searadecristo.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.searadecristo.com.br\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.searadecristo.com.br\/portal\/wp-json\/wp\/v2\/comments?post=10219"}],"version-history":[{"count":1,"href":"http:\/\/www.searadecristo.com.br\/portal\/wp-json\/wp\/v2\/posts\/10219\/revisions"}],"predecessor-version":[{"id":10221,"href":"http:\/\/www.searadecristo.com.br\/portal\/wp-json\/wp\/v2\/posts\/10219\/revisions\/10221"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.searadecristo.com.br\/portal\/wp-json\/wp\/v2\/media\/10220"}],"wp:attachment":[{"href":"http:\/\/www.searadecristo.com.br\/portal\/wp-json\/wp\/v2\/media?parent=10219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.searadecristo.com.br\/portal\/wp-json\/wp\/v2\/categories?post=10219"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.searadecristo.com.br\/portal\/wp-json\/wp\/v2\/tags?post=10219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}