{"id":10188,"date":"2024-05-19T18:59:38","date_gmt":"2024-05-19T21:59:38","guid":{"rendered":"https:\/\/www.searadecristo.com.br\/portal\/?p=10188"},"modified":"2025-02-12T06:09:39","modified_gmt":"2025-02-12T09:09:39","slug":"voce-esta-preparado-3","status":"publish","type":"post","link":"http:\/\/www.searadecristo.com.br\/portal\/voce-esta-preparado-3\/","title":{"rendered":"Voc\u00ea est\u00e1 preparado?"},"content":{"rendered":"<p><strong>EBD \u2013 <\/strong>Adolescentes<strong> &#8211; EDI\u00c7\u00c3O: 177<\/strong> &#8211; 2\u00ba Trimestre &#8211; Ano: 2024 &#8211; Editora: CPAD<\/p>\n<p><strong>LI\u00c7\u00c3O &#8211; 08<\/strong> \u2013 26 de maio de 2024<\/p>\n<p><strong>TEXTO B\u00cdBLICO<\/strong><\/p>\n<p>Mateus 25.1-13<\/p>\n<p><strong>DESTAQUE<\/strong><\/p>\n<p>\u201cE Jesus terminou, dizendo: Portanto, fiquem vigiando porque voc\u00eas n\u00e3o sabem qual ser\u00e1 o dia e a hora.\u201d\u00a0<strong>Mateus 25.13<\/strong><\/p>\n<p><strong>LEITURA DEVOCIONAL<\/strong><\/p>\n<p><strong>Segunda-feira\u00a0<\/strong>&#8211; II Pe 1.16<br \/>\n<strong>Ter\u00e7a<\/strong><strong>-feira<\/strong><strong>\u00a0<\/strong>&#8211; Mc 13.32-27<br \/>\n<strong>Quarta<\/strong><strong>-feira<\/strong><strong>\u00a0<\/strong>&#8211; I Ts 4.15-18<br \/>\n<strong>Quinta<\/strong><strong>-feira<\/strong><strong>\u00a0<\/strong>&#8211; Tt 2.13<br \/>\n<strong>Sexta\u00a0<\/strong>&#8211; I Jo 3.2,3<br \/>\n<strong>S\u00e1bado\u00a0<\/strong>&#8211; Mt 24.36,44<\/p>\n<p><strong>I. QUAL TIPO DE CRIST\u00c3O \u00c9 VOC\u00ca: COM OU SEM JU\u00cdZO?<\/strong><\/p>\n<p>Jesus disse que o Reino do C\u00e9u se assemelha a \u201c[\u2026] dez mo\u00e7as que pegaram as suas lamparinas e sa\u00edram para se encontrar com o noivo\u201d (Mt 25.1). Seguindo a narrativa, Jesus apresenta uma divis\u00e3o entre elas, dizendo que \u201ccinco eram sem ju\u00edzo, e cinco eram ajuizadas\u201d (v.2). O interessante \u00e9 que a diferencia\u00e7\u00e3o n\u00e3o est\u00e1 nem nas roupas que elas usam, nem nas suas condi\u00e7\u00f5es morais \u2013 pois todas vestiam a mesma roupa e eram igualmente virgens \u2013 mas na forma como elas se prepararam para esperar o cortejo nupcial. Ou seja, as sem ju\u00edzo, diz o texto \u201cn\u00e3o levaram \u00f3leo de reserva\u201d (v.3), enquanto que as ajuizadas, \u201clevaram vasilhas com \u00f3leo para as suas lamparinas\u201d (v.4).<\/p>\n<p>Como \u00e9 poss\u00edvel observar, apenas as mo\u00e7as com ju\u00edzo consideraram a possibilidade de uma demora por parte do noivo e, com isso, se prepararam com vasilhas extras. Acontece que o noivo realmente demorou a retornar e durante a espera, todas as dez mo\u00e7as adormeceram. Quando finalmente o noivo estava chegando, todas acordaram. Por\u00e9m, apenas cinco mo\u00e7as puderam acender suas lamparinas; e as demais estavam sem luz porque n\u00e3o tinham mais \u00f3leo. Diante disso, as cinco mo\u00e7as, com as lamparinas apagadas, sa\u00edram para tentar providenciar o \u00f3leo necess\u00e1rio.<\/p>\n<p>Entretanto, o noivo chegou e apenas as cinco mo\u00e7as ajuizadas puderam entrar com ele na festa de casamento. A partir de todo o contexto que essa hist\u00f3ria est\u00e1 inserida fica evidente que o noivo da par\u00e1bola \u00e9 Jesus e que as dez mo\u00e7as revelam duas classes de pessoas que lidam com a promessa de sua Segunda Vinda de maneiras distintas:<\/p>\n<p><strong>1- Os sem ju\u00edzos.<\/strong><em><strong>\u00a0<\/strong><\/em>Eles vivem de forma irreverente e insensata. Eles s\u00e3o descuidados com sua vida espiritual, n\u00e3o d\u00e3o valor \u00e0s disciplinas da ora\u00e7\u00e3o (I Ts 5.17), da leitura da Palavra (Jo 5.39; II Tm 3.15-17) e da comunh\u00e3o (At 2.42-47); e, por isso, n\u00e3o tem \u00f3leo de reserva.<br \/>\n<strong>2- Os ajuizados.<\/strong>\u00a0Por outro lado, os que t\u00eam ju\u00edzo s\u00e3o cuidadosos e prevenidos. Eles se preocupam com a imprevisibilidade da volta do noivo, e, por isso, guardam sempre \u00f3leo de reserva (Mt 25.4). Entendem a necessidade de estar diariamente prontos, pois o noivo pode voltar a qualquer momento (Mt 25.13). Essa par\u00e1bola nos provoca uma reflex\u00e3o: Como estamos lidando com a promessa da vinda de Cristo? Como temos nos preparado para esse grande momento?<\/p>\n<p><strong>II. O NOIVO VEM!<\/strong><\/p>\n<p>De acordo com as Escrituras \u00e9 evidente que Jesus voltar\u00e1 uma segunda vez (Jo 14.1-3; At 1.11). O que precisamos entender \u00e9 que essa Segunda Vinda se dar\u00e1 em duas fases distintas. A primeira trata-se do Arrebatamento da Igreja que ocorrer\u00e1 antes da Grande Tributa\u00e7\u00e3o, de maneira s\u00fabita (I Co 15.52) e exclusivamente para a Igreja. Nesse evento, os mortos em Cristo e os santos do Antigo Testamento ressuscitar\u00e3o primeiro, e, em seguida, os crist\u00e3os vivos ser\u00e3o transformados e, juntos, todos se encontrar\u00e3o com o Senhor nos ares (I Ts 4.16,17) para participarem do Tribunal de Cristo, receberem o galard\u00e3o (II Co 5.10) e entrarem nas\u00a0Bodas do Cordeiro\u00a0(Ap 19.7-9). J\u00e1 a segunda fase, refere-se \u00e0 vinda em gl\u00f3ria de Cristo depois da\u00a0Grande Tribula\u00e7\u00e3o\u00a0(Ap 1.7), de forma vis\u00edvel e corporal com a Igreja glorificada (Lc 21.27). Na hist\u00f3ria narrada por Jesus, as dez mo\u00e7as (as sem ju\u00edzos e as ajuizadas) foram surpreendidas com a chegada do noivo, que se deu repentinamente. Raz\u00e3o pela qual, \u00e9 correto afirmarmos que o foco de Jesus nesta par\u00e1bola \u00e9 sobre o preparo necess\u00e1rio ante ao arrebatamento da Igreja, que se dar\u00e1 em dia e hora que ningu\u00e9m sabe.<\/p>\n<p><strong>III. ESTEJA PRONTO PARA O GRANDE DIA<\/strong><\/p>\n<p>Jesus conclui sua hist\u00f3ria com a seguinte frase:\u201c[\u2026] portanto, fiquem vigiando porque voc\u00eas n\u00e3o sabem qual ser\u00e1 o dia e a hora\u201d (Mt 25.13). Tais palavras devem ser encaradas como uma advert\u00eancia sobre a necessidade de estarmos preparados para sua vinda. Afinal de contas, ela pode demorar mais tempo do que imaginamos (v.5) ou vir mais cedo do que o esperado; a \u00fanica certeza que temos \u00e9 que \u201co fim de todas as coisas est\u00e1 perto\u201d (I Pe 4.7a) e que precisamos despertar urgentemente, pois \u201c[\u2026] o momento de sermos salvos est\u00e1 mais perto agora do que quando come\u00e7amos a crer\u201d (Rm 13.11).<\/p>\n<p>Jesus brevemente voltar\u00e1! Infelizmente, alguns crist\u00e3os, seduzidos pelos incr\u00e9dulos do nosso tempo, est\u00e3o sendo levados a duvidar do car\u00e1ter daquele que fez a promessa (II Pe 3.2-10). Mas n\u00e3o devemos entregar nossa mente e cora\u00e7\u00e3o a esses ladr\u00f5es de esperan\u00e7a. Afinal de contas, fiel \u00e9 aquele que nos prometeu (Hb 10.23) e \u2018*[\u2026] um pouco mais de tempo, um pouco mesmo, e vir\u00e1 aquele que tem de vir, ele n\u00e3o vai demorar\u201d (Hb 10.37). E guardando essa esperan\u00e7a em nosso cora\u00e7\u00e3o, de acordo com Jesus, precisamos assumir duas atitudes:<\/p>\n<p><strong>1\u00b0)<\/strong>\u00a0<strong>Encher nossas vasilhas com \u00f3leo:<\/strong> Isso faz uma alus\u00e3o ao Esp\u00edrito Santo. Ou seja, devemos nos deixar ser cheios pelo Esp\u00edrito Santo se quisermos estar preparados adequadamente (Ef5.18) e vivermos uma vida de santidade.<br \/>\n<strong>2\u00b0)<\/strong>\u00a0<strong>Permanecer vigilantes:<\/strong> A Vinda ser\u00e1 inesperada (Mt 24.42,44). N\u00e3o se distraia com as coisas desse mundo. H\u00e1 algo muito maior e melhor para n\u00f3s na eternidade, mas para isso \u00e9 preciso estar atento e vigilante, pois o Diabo, nosso advers\u00e1rio, \u201c[\u2026] anda por a\u00ed como um le\u00e3o que ruge, procurando algu\u00e9m para devorar\u201d (I Pe 5.8).<\/p>\n<p><strong>CONCLUS\u00c3O<\/strong><\/p>\n<p>A nossa esperan\u00e7a n\u00e3o se baseia numa utopia criada por mentes humanas, mas em fatos revelados na Palavra de Deus. Por essa raz\u00e3o devemos estar preparados para aguardar a vinda do Senhor Jesus, pois Ele \u00e9 fiel para cumprir a sua promessa e por isso breve voltar\u00e1!<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Postado por: <\/strong>Pr. Ademilson Braga<\/p>\n<p style=\"text-align: right;\"><strong>Fonte: <\/strong>Editora CPAD<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EBD \u2013 Adolescentes &#8211; EDI\u00c7\u00c3O: 177 &#8211; 2\u00ba Trimestre &#8211; Ano: 2024 &#8211; Editora: CPAD LI\u00c7\u00c3O &#8211; 08 \u2013 26 de maio de 2024 TEXTO B\u00cdBLICO Mateus 25.1-13 DESTAQUE \u201cE Jesus terminou, dizendo: Portanto, fiquem vigiando porque voc\u00eas n\u00e3o sabem qual ser\u00e1 o dia e a hora.\u201d\u00a0Mateus 25.13 LEITURA DEVOCIONAL Segunda-feira\u00a0&#8211; II Pe 1.16 Ter\u00e7a-feira\u00a0&#8211; [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10189,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[972,7],"tags":[],"class_list":["post-10188","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-adolescente","category-e-b-d"],"_links":{"self":[{"href":"http:\/\/www.searadecristo.com.br\/portal\/wp-json\/wp\/v2\/posts\/10188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.searadecristo.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.searadecristo.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.searadecristo.com.br\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.searadecristo.com.br\/portal\/wp-json\/wp\/v2\/comments?post=10188"}],"version-history":[{"count":1,"href":"http:\/\/www.searadecristo.com.br\/portal\/wp-json\/wp\/v2\/posts\/10188\/revisions"}],"predecessor-version":[{"id":10190,"href":"http:\/\/www.searadecristo.com.br\/portal\/wp-json\/wp\/v2\/posts\/10188\/revisions\/10190"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.searadecristo.com.br\/portal\/wp-json\/wp\/v2\/media\/10189"}],"wp:attachment":[{"href":"http:\/\/www.searadecristo.com.br\/portal\/wp-json\/wp\/v2\/media?parent=10188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.searadecristo.com.br\/portal\/wp-json\/wp\/v2\/categories?post=10188"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.searadecristo.com.br\/portal\/wp-json\/wp\/v2\/tags?post=10188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}